{"id":6449,"date":"2024-03-20T23:03:25","date_gmt":"2024-03-21T06:03:25","guid":{"rendered":"https:\/\/sites.mind.uci.edu\/grill\/?p=6449"},"modified":"2026-02-25T13:32:07","modified_gmt":"2026-02-25T21:32:07","slug":"6449-2","status":"publish","type":"post","link":"https:\/\/sites.mind.uci.edu\/grill\/6449-2\/","title":{"rendered":"Want to make an IMPACT in Alzheimer\u2019s clinical trials? Apply for IMPACT-AD"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;6352&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1711000962064{padding-top: 20px !important;}&#8221; text_direction=&#8221;default&#8221;]\n<h2><a href=\"https:\/\/www.nia.nih.gov\/research\/blog\/2023\/03\/want-make-impact-alzheimers-clinical-trials-apply-impact-ad\">Want to make an IMPACT in Alzheimer\u2019s clinical trials? Apply for IMPACT-AD<\/a><\/h2>\n<p>A training course, directed by UCI MIND Director, Dr. Joshua Grill and Director of Biostatistics at USC Alzheimer&#8217;s Therapeutic Research Institute.<\/p>\n<p><a href=\"https:\/\/www.nia.nih.gov\/research\/blog\/2023\/03\/want-make-impact-alzheimers-clinical-trials-apply-impact-ad\">Click to learn more about IMPACT-AD<\/a>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;6352&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][vc_column_text css=&#8221;.vc_custom_1711000962064{padding-top: 20px !important;}&#8221; text_direction=&#8221;default&#8221;] Want to make an IMPACT in Alzheimer\u2019s clinical trials? Apply for IMPACT-AD A training course, directed by UCI MIND Director, Dr. Joshua Grill and Director of Biostatistics at USC Alzheimer&#8217;s Therapeutic Research Institute. Click to learn more about IMPACT-AD[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,32,33],"tags":[],"class_list":["post-6449","post","type-post","status-publish","format-standard","category-blog","category-in-the-news","category-uci-mind"],"_links":{"self":[{"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/posts\/6449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/comments?post=6449"}],"version-history":[{"count":2,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/posts\/6449\/revisions"}],"predecessor-version":[{"id":6798,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/posts\/6449\/revisions\/6798"}],"wp:attachment":[{"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/media?parent=6449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/categories?post=6449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.mind.uci.edu\/grill\/wp-json\/wp\/v2\/tags?post=6449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}